{"id":9959,"date":"2026-08-31T20:35:01","date_gmt":"2026-08-31T20:35:01","guid":{"rendered":"https:\/\/ledenonciateur224.com\/?p=9959"},"modified":"2026-08-31T20:35:01","modified_gmt":"2026-08-31T20:35:01","slug":"gouvernance-du-numerique-ibrahima-sory-ii-tounkara-appelle-a-reguler-sans-censurer","status":"publish","type":"post","link":"https:\/\/ledenonciateur224.com\/index.php\/gouvernance-du-numerique-ibrahima-sory-ii-tounkara-appelle-a-reguler-sans-censurer\/","title":{"rendered":"Gouvernance du num\u00e9rique : Ibrahima Sory II Tounkara appelle \u00e0 \u00ab r\u00e9guler sans censurer \u00bb"},"content":{"rendered":"<p>\u00c0 l\u2019ouverture, ce lundi, de la 12\u1d49 Assembl\u00e9e g\u00e9n\u00e9rale de la Plateforme des R\u00e9gulateurs de l\u2019Audiovisuel des pays membres de l\u2019UEMOA et de la Guin\u00e9e (PRA-UEMOA-Guin\u00e9e), la gouvernance du num\u00e9rique s\u2019est impos\u00e9e au c\u0153ur des \u00e9changes. Devant les r\u00e9gulateurs de la r\u00e9gion, le ministre de la Justice et des Droits de l\u2019Homme, Garde des Sceaux, Ibrahima Sory II Tounkara, a mis en lumi\u00e8re les opportunit\u00e9s offertes par le num\u00e9rique, mais aussi les risques croissants qui l\u2019accompagnent.<\/p>\n<p>Le ministre a notamment soulign\u00e9 le r\u00f4le des r\u00e9seaux sociaux dans la d\u00e9mocratisation de l\u2019acc\u00e8s \u00e0 l\u2019information et dans le renforcement de la participation citoyenne. Mais cette \u00e9volution s\u2019accompagne, selon lui, de d\u00e9rives pr\u00e9occupantes : d\u00e9sinformation, discours de haine, manipulation de l\u2019opinion et cybercriminalit\u00e9.<\/p>\n<p>\u00ab Les r\u00e9seaux sociaux ont \u00e9largi l\u2019acc\u00e8s \u00e0 l\u2019information, favoris\u00e9 l\u2019expression citoyenne et ouvert de nouvelles possibilit\u00e9s \u00e0 notre jeunesse. Mais ils sont aussi devenus des vecteurs de d\u00e9sinformation, de discours de haine, de manipulation et de cybercriminalit\u00e9 \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Le Garde des Sceaux a \u00e9galement attir\u00e9 l\u2019attention sur l\u2019essor de l\u2019intelligence artificielle et des hypertrucages (deepfakes), capables de rendre les fausses informations toujours plus cr\u00e9dibles et difficiles \u00e0 d\u00e9tecter.<\/p>\n<p>Pour Ibrahima Sory II Tounkara, ces nouvelles technologies peuvent fragiliser la confiance dans les institutions, attiser les tensions et affecter la stabilit\u00e9 des \u00c9tats. La cybers\u00e9curit\u00e9 doit ainsi \u00eatre consid\u00e9r\u00e9e bien au-del\u00e0 de sa seule dimension technique.<\/p>\n<p>\u00ab La cybers\u00e9curit\u00e9 n\u2019est donc plus seulement une question technique. Elle est un enjeu de souverainet\u00e9, de protection des droits et de coh\u00e9sion sociale \u00bb, a insist\u00e9 le ministre.<\/p>\n<p>Face \u00e0 ces d\u00e9fis, le ministre a plaid\u00e9 pour une r\u00e9gulation \u00e9quilibr\u00e9e du num\u00e9rique. L\u2019objectif, selon lui, est de prot\u00e9ger les citoyens et les institutions sans compromettre les libert\u00e9s fondamentales.<\/p>\n<p>Il a ainsi appel\u00e9 les r\u00e9gulateurs \u00e0 trouver le juste \u00e9quilibre entre libert\u00e9 d\u2019expression, protection de l\u2019espace public et lutte contre les abus.<\/p>\n<p>\u00ab Prot\u00e9ger sans \u00e9touffer, r\u00e9guler sans censurer, et sanctionner les abus sans affaiblir la libert\u00e9 d\u2019expression \u00bb, a martel\u00e9 Ibrahima Sory II Tounkara.<\/p>\n<p>Pour le Garde des Sceaux, la libert\u00e9 d\u2019expression demeure un principe essentiel, mais elle ne saurait servir de couverture aux appels \u00e0 la violence, \u00e0 la manipulation organis\u00e9e ou aux atteintes \u00e0 la dignit\u00e9 humaine.<\/p>\n<p>\u00c0 travers cette intervention, le ministre invite ainsi les acteurs de la r\u00e9gulation audiovisuelle et num\u00e9rique de l\u2019espace UEMOA-Guin\u00e9e \u00e0 construire une gouvernance capable de concilier innovation technologique, s\u00e9curit\u00e9, souverainet\u00e9 num\u00e9rique et respect des droits fondamentaux.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>AMC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019ouverture, ce lundi, de la 12\u1d49 Assembl\u00e9e g\u00e9n\u00e9rale de la Plateforme des R\u00e9gulateurs de l\u2019Audiovisuel des pays membres de l\u2019UEMOA et de la Guin\u00e9e (PRA-UEMOA-Guin\u00e9e), la gouvernance du num\u00e9rique s\u2019est impos\u00e9e au c\u0153ur des \u00e9changes. Devant les r\u00e9gulateurs de la r\u00e9gion, le ministre de la Justice et des Droits de l\u2019Homme, Garde des Sceaux, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30,24],"tags":[1857,1134],"class_list":["post-9959","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faits-divers","category-news","tag-cyberspace","tag-numerique"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/ledenonciateur224.com\/wp-content\/uploads\/2026\/08\/ib-sory.jpeg","_links":{"self":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts\/9959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/comments?post=9959"}],"version-history":[{"count":1,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts\/9959\/revisions"}],"predecessor-version":[{"id":9961,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts\/9959\/revisions\/9961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/media\/9960"}],"wp:attachment":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/media?parent=9959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/categories?post=9959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/tags?post=9959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}