{"id":9984,"date":"2026-09-02T08:54:33","date_gmt":"2026-09-02T08:54:33","guid":{"rendered":"https:\/\/ledenonciateur224.com\/?p=9984"},"modified":"2026-09-02T08:54:33","modified_gmt":"2026-09-02T08:54:33","slug":"forces-armees-guineennes-le-ministere-de-la-defense-precise-les-profils-recherches-et-les-conditions-de-recrutement","status":"publish","type":"post","link":"https:\/\/ledenonciateur224.com\/index.php\/forces-armees-guineennes-le-ministere-de-la-defense-precise-les-profils-recherches-et-les-conditions-de-recrutement\/","title":{"rendered":"Forces arm\u00e9es guin\u00e9ennes : le minist\u00e8re de la D\u00e9fense pr\u00e9cise les profils recherch\u00e9s et les conditions de recrutement"},"content":{"rendered":"<p>Dans le cadre du concours de recrutement au sein des Forces arm\u00e9es guin\u00e9ennes, le minist\u00e8re de la D\u00e9fense nationale a apport\u00e9, mardi 1er septembre 2026, des pr\u00e9cisions sur les profils recherch\u00e9s et les modalit\u00e9s de candidature.<\/p>\n<p>Selon le ministre d\u00e9l\u00e9gu\u00e9 aupr\u00e8s du Pr\u00e9sident de la R\u00e9publique, charg\u00e9 de la D\u00e9fense nationale, Ibrahima Kalil Cond\u00e9, le recrutement cible exclusivement deux cat\u00e9gories de professionnels sp\u00e9cialis\u00e9s : les ing\u00e9nieurs et les m\u00e9decins sp\u00e9cialistes.<\/p>\n<p>Chez les ing\u00e9nieurs, plusieurs domaines sont concern\u00e9s, notamment le g\u00e9nie civil et les travaux publics, l\u2019\u00e9lectrotechnique, la m\u00e9canique, l\u2019agronomie, la topographie, la g\u00e9ologie, l\u2019architecture, le g\u00e9nie \u00e9lectrique, les t\u00e9l\u00e9communications, la radio, la cybers\u00e9curit\u00e9, l\u2019\u00e9lectronique, la robotique et les drones, ainsi que l\u2019environnement et le g\u00e9nie rural.<\/p>\n<p>Pour les m\u00e9decins, les sp\u00e9cialit\u00e9s retenues comprennent entre autres la chirurgie digestive et visc\u00e9rale, la chirurgie maxillo-faciale, l\u2019ORL, l\u2019anesth\u00e9sie-r\u00e9animation, la cardiologie, la neurologie, la psychiatrie, la pneumologie, la phtisiologie et l\u2019endocrinologie. La radiologie et l\u2019imagerie m\u00e9dicale, la m\u00e9decine l\u00e9gale ainsi que la m\u00e9decine v\u00e9t\u00e9rinaire sont \u00e9galement concern\u00e9es.<\/p>\n<p>La limite d\u2019\u00e2ge est fix\u00e9e \u00e0 45 ans pour les m\u00e9decins sp\u00e9cialistes et \u00e0 35 ans pour les ing\u00e9nieurs.<\/p>\n<p>Les candidats doivent d\u00e9poser leurs dossiers au camp Almamy Samory Tour\u00e9, du 1er au 30 septembre 2026, du lundi au vendredi, entre 9h et 16h30.<\/p>\n<p>Le dossier comprend notamment une demande manuscrite adress\u00e9e au ministre charg\u00e9 de la D\u00e9fense nationale, une copie l\u00e9galis\u00e9e du dipl\u00f4me, un extrait d\u2019acte de naissance biom\u00e9trique, une copie de la carte nationale d\u2019identit\u00e9 biom\u00e9trique, un casier judiciaire et un certificat de r\u00e9sidence datant de moins de trois mois, un certificat m\u00e9dical de visite et contre-visite, ainsi que quatre photos d\u2019identit\u00e9 sur fond rouge.<\/p>\n<p>Le minist\u00e8re de la D\u00e9fense nationale met enfin en garde les candidats contre toute tentative de fraude. Les documents fournis feront l\u2019objet d\u2019un contr\u00f4le rigoureux d\u2019authentification.<\/p>\n<p>Toute falsification ou utilisation de faux documents expose les auteurs et leurs \u00e9ventuels complices \u00e0 des poursuites judiciaires, conform\u00e9ment \u00e0 la l\u00e9gislation en vigueur en R\u00e9publique de Guin\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ledenonciateur224.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du concours de recrutement au sein des Forces arm\u00e9es guin\u00e9ennes, le minist\u00e8re de la D\u00e9fense nationale a apport\u00e9, mardi 1er septembre 2026, des pr\u00e9cisions sur les profils recherch\u00e9s et les modalit\u00e9s de candidature. Selon le ministre d\u00e9l\u00e9gu\u00e9 aupr\u00e8s du Pr\u00e9sident de la R\u00e9publique, charg\u00e9 de la D\u00e9fense nationale, Ibrahima Kalil Cond\u00e9, le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9985,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[30,24],"tags":[455,731],"class_list":["post-9984","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faits-divers","category-news","tag-armees-guineennes","tag-recemment"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/ledenonciateur224.com\/wp-content\/uploads\/2026\/09\/kalilconde2026-07-30-at-081427.jpeg","_links":{"self":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts\/9984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/comments?post=9984"}],"version-history":[{"count":1,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts\/9984\/revisions"}],"predecessor-version":[{"id":9986,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/posts\/9984\/revisions\/9986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/media\/9985"}],"wp:attachment":[{"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/media?parent=9984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/categories?post=9984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ledenonciateur224.com\/index.php\/wp-json\/wp\/v2\/tags?post=9984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}